{"id":15,"count":3,"description":"","link":"https:\/\/medisure.agency\/articles\/tag\/medicare-supplement\/","name":"Medicare Supplement","slug":"medicare-supplement","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Medicare Supplement Archives - The Medisure Agency Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medisure.agency\/articles\/tag\/medicare-supplement\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Medicare Supplement Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medisure.agency\/articles\/tag\/medicare-supplement\/\" \/>\n<meta property=\"og:site_name\" content=\"The Medisure Agency Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@medisureagency\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/tag\\\/medicare-supplement\\\/\",\"url\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/tag\\\/medicare-supplement\\\/\",\"name\":\"Medicare Supplement Archives - The Medisure Agency Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/tag\\\/medicare-supplement\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/tag\\\/medicare-supplement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Medicare Supplement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/#website\",\"url\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/\",\"name\":\"Our Blog\",\"description\":\"A blog that matters\",\"publisher\":{\"@id\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/#organization\",\"name\":\"Our Blog\",\"url\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Medisure-Logo-PNG-TP.png\",\"contentUrl\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Medisure-Logo-PNG-TP.png\",\"width\":500,\"height\":500,\"caption\":\"Our Blog\"},\"image\":{\"@id\":\"https:\\\/\\\/medisure.agency\\\/articles\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/medicare.medisure.agency\",\"https:\\\/\\\/x.com\\\/medisureagency\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/medisure-agency\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC6tq39ChOw2f0v5Sh03BETg\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Medicare Supplement Archives - The Medisure Agency Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medisure.agency\/articles\/tag\/medicare-supplement\/","og_locale":"en_US","og_type":"article","og_title":"Medicare Supplement Archives","og_url":"https:\/\/medisure.agency\/articles\/tag\/medicare-supplement\/","og_site_name":"The Medisure Agency Blog","twitter_card":"summary_large_image","twitter_site":"@medisureagency","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/medisure.agency\/articles\/tag\/medicare-supplement\/","url":"https:\/\/medisure.agency\/articles\/tag\/medicare-supplement\/","name":"Medicare Supplement Archives - The Medisure Agency Blog","isPartOf":{"@id":"https:\/\/medisure.agency\/articles\/#website"},"breadcrumb":{"@id":"https:\/\/medisure.agency\/articles\/tag\/medicare-supplement\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/medisure.agency\/articles\/tag\/medicare-supplement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/medisure.agency\/articles\/"},{"@type":"ListItem","position":2,"name":"Medicare Supplement"}]},{"@type":"WebSite","@id":"https:\/\/medisure.agency\/articles\/#website","url":"https:\/\/medisure.agency\/articles\/","name":"Our Blog","description":"A blog that matters","publisher":{"@id":"https:\/\/medisure.agency\/articles\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medisure.agency\/articles\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/medisure.agency\/articles\/#organization","name":"Our Blog","url":"https:\/\/medisure.agency\/articles\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/medisure.agency\/articles\/#\/schema\/logo\/image\/","url":"https:\/\/medisure.agency\/articles\/wp-content\/uploads\/2022\/07\/Medisure-Logo-PNG-TP.png","contentUrl":"https:\/\/medisure.agency\/articles\/wp-content\/uploads\/2022\/07\/Medisure-Logo-PNG-TP.png","width":500,"height":500,"caption":"Our Blog"},"image":{"@id":"https:\/\/medisure.agency\/articles\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/medicare.medisure.agency","https:\/\/x.com\/medisureagency","https:\/\/www.linkedin.com\/company\/medisure-agency\/","https:\/\/www.youtube.com\/channel\/UC6tq39ChOw2f0v5Sh03BETg"]}]}},"_links":{"self":[{"href":"https:\/\/medisure.agency\/articles\/wp-json\/wp\/v2\/tags\/15","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medisure.agency\/articles\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/medisure.agency\/articles\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/medisure.agency\/articles\/wp-json\/wp\/v2\/posts?tags=15"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}